{"id":15510,"date":"2015-06-07T17:19:00","date_gmt":"2015-06-07T15:19:00","guid":{"rendered":"https:\/\/dev.beneggiassociati.com\/2015\/06\/07\/jobs-act-il-modello-unilav-conciliazione-e-on-line\/"},"modified":"2015-06-07T17:19:00","modified_gmt":"2015-06-07T15:19:00","slug":"jobs-act-il-modello-unilav-conciliazione-e-on-line","status":"publish","type":"post","link":"https:\/\/beneggiassociati.com\/en\/jobs-act-il-modello-unilav-conciliazione-e-on-line\/","title":{"rendered":"Jobs act, il modello UNILAV-conciliazione \u00e8 on line"},"content":{"rendered":"<p>L&#8217;articolo 6 del D.Lgs. 4 marzo 2015, n. 23 (Job acts), dispone che, in caso di licenziamento dei lavoratori soggetti al contratto a tutele crescenti, per evitare il giudizio, il datore pu\u00f2 offrire al lavoratore, entro 60 giorni dal recesso, presso una sede protetta o una commissione di certificazione, un importo esente da Irpef e contributi pari a 1 mensilit\u00e0 della retribuzione di riferimento per il calcolo del TFR per ogni anno di servizio, in misura non inferiore a 2 e non superiore a 18 mensilit\u00e0, mediante consegna al lavoratore di un assegno circolare. Tale importo \u00e8 dimezzato e non pu\u00f2 superare le 6 mensilit\u00e0 nelle PMI.<br \/>\nPoich\u00e9 la stessa norma dispone che la comunicazione obbligatoria telematica di cessazione del rapporto \u00e8 integrata da un&#8217;ulteriore comunicazione, da effettuarsi da parte del datore entro 65 giorni dalla risoluzione del rapporto, nella quale va indicata l&#8217;avvenuta ovvero la non avvenuta conciliazione, il Ministero ha reso noto che a partire dal 1\u00b0 giugno prossimo sul portale Cliclavoro sar\u00e0 disponibile una nuova applicazione, denominata &#8220;UNILAV_Conciliazione&#8221; con la quale i datori di lavoro dovranno comunicare le prescritte informazioni circa il procedimento di conciliazione di cui sopra; l&#8217;omesso invio della comunicazione \u00e8 soggetto al pagamento di una sanzione amministrativa pecuniaria di importo compreso tra 100 e 500 euro per ogni lavoratore interessato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;articolo 6 del D.Lgs. 4 marzo 2015, n. 23 (Job acts), dispone che, in caso di licenziamento dei lavoratori soggetti al contratto a tutele crescenti, per evitare il giudizio, il datore pu\u00f2 offrire al lavoratore, entro 60 giorni dal recesso, presso una sede protetta o una commissione di certificazione, un importo esente da Irpef e [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":409,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[16],"tags":[],"class_list":["post-15510","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jobs act, il modello UNILAV-conciliazione \u00e8 on line - Beneggi &amp; Associati<\/title>\n<meta name=\"description\" content=\"L&#039;articolo 6 del D.Lgs. 4 marzo 2015, n. 23 (Job acts), dispone che, in caso di licenziamento dei lavoratori soggetti al contratto a tutele crescenti, per\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beneggiassociati.com\/en\/jobs-act-il-modello-unilav-conciliazione-e-on-line\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jobs act, il modello UNILAV-conciliazione \u00e8 on line - Beneggi &amp; Associati\" \/>\n<meta property=\"og:description\" content=\"L&#039;articolo 6 del D.Lgs. 4 marzo 2015, n. 23 (Job acts), dispone che, in caso di licenziamento dei lavoratori soggetti al contratto a tutele crescenti, per\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beneggiassociati.com\/en\/jobs-act-il-modello-unilav-conciliazione-e-on-line\/\" \/>\n<meta property=\"og:site_name\" content=\"Beneggi &amp; Associati\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-07T15:19:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beneggiassociati.com\/wp-content\/uploads\/2025\/07\/single-post-beneggi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"823\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tiziano Beneggi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tiziano Beneggi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/beneggiassociati.com\\\/en\\\/jobs-act-il-modello-unilav-conciliazione-e-on-line\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beneggiassociati.com\\\/en\\\/jobs-act-il-modello-unilav-conciliazione-e-on-line\\\/\"},\"author\":{\"name\":\"Tiziano Beneggi\",\"@id\":\"https:\\\/\\\/beneggiassociati.com\\\/en\\\/#\\\/schema\\\/person\\\/828daacfa37b359e89e981f920072004\"},\"headline\":\"Jobs act, il modello UNILAV-conciliazione \u00e8 on line\",\"datePublished\":\"2015-06-07T15:19:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/beneggiassociati.com\\\/en\\\/jobs-act-il-modello-unilav-conciliazione-e-on-line\\\/\"},\"wordCount\":213,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/beneggiassociati.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/beneggiassociati.com\\\/en\\\/jobs-act-il-modello-unilav-conciliazione-e-on-line\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beneggiassociati.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/single-post-beneggi.jpg\",\"articleSection\":[\"ARCHIVIO\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/beneggiassociati.com\\\/en\\\/jobs-act-il-modello-unilav-conciliazione-e-on-line\\\/\",\"url\":\"https:\\\/\\\/beneggiassociati.com\\\/en\\\/jobs-act-il-modello-unilav-conciliazione-e-on-line\\\/\",\"name\":\"Jobs act, il modello UNILAV-conciliazione \u00e8 on line - Beneggi &amp; Associati\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beneggiassociati.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/beneggiassociati.com\\\/en\\\/jobs-act-il-modello-unilav-conciliazione-e-on-line\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/beneggiassociati.com\\\/en\\\/jobs-act-il-modello-unilav-conciliazione-e-on-line\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beneggiassociati.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/single-post-beneggi.jpg\",\"datePublished\":\"2015-06-07T15:19:00+00:00\",\"description\":\"L'articolo 6 del D.Lgs. 4 marzo 2015, n. 23 (Job acts), dispone che, in caso di licenziamento dei lavoratori soggetti al contratto a tutele crescenti, per\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/beneggiassociati.com\\\/en\\\/jobs-act-il-modello-unilav-conciliazione-e-on-line\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/beneggiassociati.com\\\/en\\\/jobs-act-il-modello-unilav-conciliazione-e-on-line\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/beneggiassociati.com\\\/en\\\/jobs-act-il-modello-unilav-conciliazione-e-on-line\\\/#primaryimage\",\"url\":\"https:\\\/\\\/beneggiassociati.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/single-post-beneggi.jpg\",\"contentUrl\":\"https:\\\/\\\/beneggiassociati.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/single-post-beneggi.jpg\",\"width\":1280,\"height\":823},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/beneggiassociati.com\\\/en\\\/jobs-act-il-modello-unilav-conciliazione-e-on-line\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/beneggiassociati.com\\\/en\\\/?page_id=24163\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jobs act, il modello UNILAV-conciliazione \u00e8 on line\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/beneggiassociati.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/beneggiassociati.com\\\/en\\\/\",\"name\":\"Beneggi e associati\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/beneggiassociati.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/beneggiassociati.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/beneggiassociati.com\\\/en\\\/#organization\",\"name\":\"Beneggi e associati\",\"url\":\"https:\\\/\\\/beneggiassociati.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/beneggiassociati.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/beneggiassociati.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/beneggi-logo.png\",\"contentUrl\":\"https:\\\/\\\/beneggiassociati.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/beneggi-logo.png\",\"width\":141,\"height\":87,\"caption\":\"Beneggi e associati\"},\"image\":{\"@id\":\"https:\\\/\\\/beneggiassociati.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/beneggiassociati.com\\\/en\\\/#\\\/schema\\\/person\\\/828daacfa37b359e89e981f920072004\",\"name\":\"Tiziano Beneggi\",\"url\":\"https:\\\/\\\/beneggiassociati.com\\\/en\\\/author\\\/tizianobeneggiassociati-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jobs act, il modello UNILAV-conciliazione \u00e8 on line - Beneggi &amp; Associati","description":"L'articolo 6 del D.Lgs. 4 marzo 2015, n. 23 (Job acts), dispone che, in caso di licenziamento dei lavoratori soggetti al contratto a tutele crescenti, per","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beneggiassociati.com\/en\/jobs-act-il-modello-unilav-conciliazione-e-on-line\/","og_locale":"en_US","og_type":"article","og_title":"Jobs act, il modello UNILAV-conciliazione \u00e8 on line - Beneggi &amp; Associati","og_description":"L'articolo 6 del D.Lgs. 4 marzo 2015, n. 23 (Job acts), dispone che, in caso di licenziamento dei lavoratori soggetti al contratto a tutele crescenti, per","og_url":"https:\/\/beneggiassociati.com\/en\/jobs-act-il-modello-unilav-conciliazione-e-on-line\/","og_site_name":"Beneggi &amp; Associati","article_published_time":"2015-06-07T15:19:00+00:00","og_image":[{"width":1280,"height":823,"url":"https:\/\/beneggiassociati.com\/wp-content\/uploads\/2025\/07\/single-post-beneggi.jpg","type":"image\/jpeg"}],"author":"Tiziano Beneggi","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Tiziano Beneggi","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/beneggiassociati.com\/en\/jobs-act-il-modello-unilav-conciliazione-e-on-line\/#article","isPartOf":{"@id":"https:\/\/beneggiassociati.com\/en\/jobs-act-il-modello-unilav-conciliazione-e-on-line\/"},"author":{"name":"Tiziano Beneggi","@id":"https:\/\/beneggiassociati.com\/en\/#\/schema\/person\/828daacfa37b359e89e981f920072004"},"headline":"Jobs act, il modello UNILAV-conciliazione \u00e8 on line","datePublished":"2015-06-07T15:19:00+00:00","mainEntityOfPage":{"@id":"https:\/\/beneggiassociati.com\/en\/jobs-act-il-modello-unilav-conciliazione-e-on-line\/"},"wordCount":213,"commentCount":0,"publisher":{"@id":"https:\/\/beneggiassociati.com\/en\/#organization"},"image":{"@id":"https:\/\/beneggiassociati.com\/en\/jobs-act-il-modello-unilav-conciliazione-e-on-line\/#primaryimage"},"thumbnailUrl":"https:\/\/beneggiassociati.com\/wp-content\/uploads\/2025\/07\/single-post-beneggi.jpg","articleSection":["ARCHIVIO"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/beneggiassociati.com\/en\/jobs-act-il-modello-unilav-conciliazione-e-on-line\/","url":"https:\/\/beneggiassociati.com\/en\/jobs-act-il-modello-unilav-conciliazione-e-on-line\/","name":"Jobs act, il modello UNILAV-conciliazione \u00e8 on line - Beneggi &amp; Associati","isPartOf":{"@id":"https:\/\/beneggiassociati.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/beneggiassociati.com\/en\/jobs-act-il-modello-unilav-conciliazione-e-on-line\/#primaryimage"},"image":{"@id":"https:\/\/beneggiassociati.com\/en\/jobs-act-il-modello-unilav-conciliazione-e-on-line\/#primaryimage"},"thumbnailUrl":"https:\/\/beneggiassociati.com\/wp-content\/uploads\/2025\/07\/single-post-beneggi.jpg","datePublished":"2015-06-07T15:19:00+00:00","description":"L'articolo 6 del D.Lgs. 4 marzo 2015, n. 23 (Job acts), dispone che, in caso di licenziamento dei lavoratori soggetti al contratto a tutele crescenti, per","breadcrumb":{"@id":"https:\/\/beneggiassociati.com\/en\/jobs-act-il-modello-unilav-conciliazione-e-on-line\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beneggiassociati.com\/en\/jobs-act-il-modello-unilav-conciliazione-e-on-line\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/beneggiassociati.com\/en\/jobs-act-il-modello-unilav-conciliazione-e-on-line\/#primaryimage","url":"https:\/\/beneggiassociati.com\/wp-content\/uploads\/2025\/07\/single-post-beneggi.jpg","contentUrl":"https:\/\/beneggiassociati.com\/wp-content\/uploads\/2025\/07\/single-post-beneggi.jpg","width":1280,"height":823},{"@type":"BreadcrumbList","@id":"https:\/\/beneggiassociati.com\/en\/jobs-act-il-modello-unilav-conciliazione-e-on-line\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/beneggiassociati.com\/en\/?page_id=24163"},{"@type":"ListItem","position":2,"name":"Jobs act, il modello UNILAV-conciliazione \u00e8 on line"}]},{"@type":"WebSite","@id":"https:\/\/beneggiassociati.com\/en\/#website","url":"https:\/\/beneggiassociati.com\/en\/","name":"Beneggi e associati","description":"","publisher":{"@id":"https:\/\/beneggiassociati.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beneggiassociati.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/beneggiassociati.com\/en\/#organization","name":"Beneggi e associati","url":"https:\/\/beneggiassociati.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/beneggiassociati.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/beneggiassociati.com\/wp-content\/uploads\/2025\/07\/beneggi-logo.png","contentUrl":"https:\/\/beneggiassociati.com\/wp-content\/uploads\/2025\/07\/beneggi-logo.png","width":141,"height":87,"caption":"Beneggi e associati"},"image":{"@id":"https:\/\/beneggiassociati.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/beneggiassociati.com\/en\/#\/schema\/person\/828daacfa37b359e89e981f920072004","name":"Tiziano Beneggi","url":"https:\/\/beneggiassociati.com\/en\/author\/tizianobeneggiassociati-com\/"}]}},"_links":{"self":[{"href":"https:\/\/beneggiassociati.com\/en\/wp-json\/wp\/v2\/posts\/15510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beneggiassociati.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beneggiassociati.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beneggiassociati.com\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/beneggiassociati.com\/en\/wp-json\/wp\/v2\/comments?post=15510"}],"version-history":[{"count":0,"href":"https:\/\/beneggiassociati.com\/en\/wp-json\/wp\/v2\/posts\/15510\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beneggiassociati.com\/en\/wp-json\/wp\/v2\/media\/409"}],"wp:attachment":[{"href":"https:\/\/beneggiassociati.com\/en\/wp-json\/wp\/v2\/media?parent=15510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beneggiassociati.com\/en\/wp-json\/wp\/v2\/categories?post=15510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beneggiassociati.com\/en\/wp-json\/wp\/v2\/tags?post=15510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}